{"id":1003,"date":"2011-07-11T23:57:00","date_gmt":"2011-07-12T02:57:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2011\/07\/11\/vasco-segue-lider-mesmo-folgando-na-rodada-modalidade-dadinho\/"},"modified":"2011-07-11T23:57:00","modified_gmt":"2011-07-12T02:57:00","slug":"vasco-segue-lider-mesmo-folgando-na-rodada-modalidade-dadinho","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2011\/07\/11\/vasco-segue-lider-mesmo-folgando-na-rodada-modalidade-dadinho\/","title":{"rendered":"VASCO SEGUE L\u00cdDER MESMO FOLGANDO NA RODADA &#8211; MODALIDADE DADINHO"},"content":{"rendered":"<p><a href=\"http:\/\/2.bp.blogspot.com\/-uV3sztvFlfM\/Thu4PlKCScI\/AAAAAAAABLo\/2i1CvT2e00E\/s1600\/Dadinho%2B-%2BVasco%2Bx%2BRiver.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5628294737141320130\" src=\"http:\/\/2.bp.blogspot.com\/-uV3sztvFlfM\/Thu4PlKCScI\/AAAAAAAABLo\/2i1CvT2e00E\/s320\/Dadinho%2B-%2BVasco%2Bx%2BRiver.jpg\" style=\"cursor: hand; cursor: pointer; display: block; height: 240px; margin: 0px auto 10px; text-align: center; width: 320px;\" \/><\/a><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\">Foram disputadas no \u00faltimo domingo as partidas v\u00e1lidas pela 5\u00aa rodada do <b>Campeonato Estadual de Equipes &#8211; Modalidade Dadinho<\/b>. O Vasco da Gama continua na lideran\u00e7a apesar de n\u00e3o ter jogado.<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<p><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\"><a href=\"http:\/\/www.blogger.com\/blogger.g?blogID=2284054624789208982\" name=\"more\"><\/a><br \/><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\">Na Tijuca o <b>America <\/b>venceu o <b>Flamengo <\/b>por 25 x 18 e mesmo continuando na 4\u00aa coloca\u00e7\u00e3o, diminuiu para tr\u00eas pontos a diferen\u00e7a para o l\u00edder do Estadual. Enquanto isso a equipe rubro-negra n\u00e3o aproveitou a oportunidade de assumir a lideran\u00e7a e segue em 2\u00ba lugar.<\/span><\/div>\n<p><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\"><br \/><\/span><\/div>\n<p><span style=\"color: #222222; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px;\"><\/p>\n<div style=\"text-align: justify;\">Em Piedade o <b>River <\/b>ganhou a partida diante da <b>ADDP &#8211; Cabo Frio <\/b>por 34 x 10 e manteve-se em 3\u00ba lugar, por uma diferen\u00e7a de quatro vit\u00f3rias no saldo. J\u00e1 o clube da Regi\u00e3o dos Lagos \u00e9 a \u00fanica que n\u00e3o venceu no torneio e agora caiu para a lanterna do torneio.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Em Duque de Caxias quem levou a melhor foi o <b>Fluminense<\/b>, que derrotou a equipe mandante do<b> Clube dos 500<\/b> por 24 x 11 e continuou na 5\u00aa posi\u00e7\u00e3o, empatado em n\u00famero de pontos com o 4\u00ba lugar. Com a derrota o 500 caiu uma posi\u00e7\u00e3o, aparecendo em 8\u00ba.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Em Nova Friburgo o <b>Friburguense <\/b>conseguiu sua primeira vit\u00f3ria diante da<b>ASBAC <\/b>por 20 x 16. Com isso a equipe largou a lanterna desta primeira fase e subiu para o 7\u00ba lugar, enquanto a associa\u00e7\u00e3o do Andara\u00ed segue em 6\u00ba, mas com uma diferen\u00e7a de seis pontos para o G4.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Mesmo tendo folgado nesta rodada o <b>Vasco da Gama<\/b> ainda est\u00e1 na lideran\u00e7a do Estadual, vencendo todas as quatro partidas que disputou. A classifica\u00e7\u00e3o da primeira fase est\u00e1 assim:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/2.bp.blogspot.com\/-jeCUatD4enM\/Thsb5sgnAkI\/AAAAAAAAFcM\/U5fqHKCZgaA\/s1600\/Classifica%25C3%25A7%25C3%25A3o+5%25C2%25AA+Rodada.jpg\" style=\"color: #3d85c6; margin-left: 1em; margin-right: 1em; text-decoration: none;\"><img decoding=\"async\" border=\"0\" height=\"142\" src=\"http:\/\/2.bp.blogspot.com\/-jeCUatD4enM\/Thsb5sgnAkI\/AAAAAAAAFcM\/U5fqHKCZgaA\/s320\/Classifica%25C3%25A7%25C3%25A3o+5%25C2%25AA+Rodada.jpg\" style=\"-webkit-box-shadow: rgba(0, 0, 0, 0.0976563) 1px 1px 5px; background-attachment: initial; background-clip: initial; background-color: transparent; background-image: initial; background-origin: initial; background-position: initial initial; background-repeat: initial initial; border-bottom-color: transparent; border-bottom-style: solid; border-bottom-width: 1px; border-color: initial; border-left-color: transparent; border-left-style: solid; border-left-width: 1px; border-right-color: transparent; border-right-style: solid; border-right-width: 1px; border-top-color: transparent; border-top-style: solid; border-top-width: 1px; border-width: initial; box-shadow: rgba(0, 0, 0, 0.0976563) 1px 1px 5px; padding-bottom: 5px; padding-left: 5px; padding-right: 5px; padding-top: 5px; position: relative;\" width=\"320\" \/><\/a><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A pr\u00f3xima rodada ser\u00e1 ainda neste m\u00eas, marcada para o pr\u00f3ximo dia 24.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Fonte: www.futmesario.com<\/div>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram disputadas no \u00faltimo domingo as partidas v\u00e1lidas pela 5\u00aa rodada do Campeonato Estadual de Equipes &#8211; Modalidade Dadinho. O Vasco da Gama continua na lideran\u00e7a apesar de n\u00e3o ter jogado. Na Tijuca o America venceu o Flamengo por 25 x 18 e mesmo continuando na 4\u00aa coloca\u00e7\u00e3o, diminuiu para tr\u00eas pontos a diferen\u00e7a para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[82,8],"tags":[],"class_list":["post-1003","post","type-post","status-publish","format-standard","hentry","category-estaduais-de-clubes-2011","category-modalidade-dadinho","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1003"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1003"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1003\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}