{"id":1108,"date":"2011-02-19T20:49:00","date_gmt":"2011-02-19T22:49:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2011\/02\/19\/thiago-rodrigues-e-bruno-romar-sao-destaques-na-volta-do-vasco-ao-dadinho\/"},"modified":"2011-02-19T20:49:00","modified_gmt":"2011-02-19T22:49:00","slug":"thiago-rodrigues-e-bruno-romar-sao-destaques-na-volta-do-vasco-ao-dadinho","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2011\/02\/19\/thiago-rodrigues-e-bruno-romar-sao-destaques-na-volta-do-vasco-ao-dadinho\/","title":{"rendered":"THIAGO RODRIGUES E BRUNO ROMAR S\u00c3O DESTAQUES NA VOLTA DO VASCO AO DADINHO."},"content":{"rendered":"<p><a href=\"http:\/\/4.bp.blogspot.com\/-C18dDySzzIU\/TWBXSl0rirI\/AAAAAAAABBk\/A_xQiKdfFAk\/s1600\/DADINHO.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5575552315587005106\" src=\"http:\/\/4.bp.blogspot.com\/-C18dDySzzIU\/TWBXSl0rirI\/AAAAAAAABBk\/A_xQiKdfFAk\/s320\/DADINHO.jpg\" style=\"cursor: hand; cursor: pointer; display: block; height: 240px; margin: 0px auto 10px; text-align: center; width: 320px;\" \/><\/a><span style=\"color: #292929;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"color: #292929;\"><span>Foi realizada no \u00faltimo dia 12\/02 na AABB- Tijuca,  a 1\u00aa Etapa do Estadual Individual da Modalidade DADINHO.<\/span><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #292929;\"><span>A competi\u00e7\u00e3o marcou o retorno do CR Vasco da Gama a modalidade.<\/span><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #292929;\"><span>Destaque para os atletas Thiago Rodrigues e Bruno Romar que asseguraram o acesso a s\u00e9rie ouro, ap\u00f3s terem terminado a disputa da s\u00e9rie prata na 2\u00aa e 4\u00aa coloca\u00e7\u00f5es respectivamente.<\/span><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #292929;\"><span>Cumpre ressaltar que a s\u00e9rie PRATA foi disputada por 50 atletas, onde somente os 4 primeiros colocados asseguravam o acesso a s\u00e9rie OURO, 20 permaneceram na prata e os demais foram rebaixados e na pr\u00f3xima etapa disputar\u00e3o a s\u00e9rie BRONZE.<\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foi realizada no \u00faltimo dia 12\/02 na AABB- Tijuca, a 1\u00aa Etapa do Estadual Individual da Modalidade DADINHO. A competi\u00e7\u00e3o marcou o retorno do CR Vasco da Gama a modalidade. Destaque para os atletas Thiago Rodrigues e Bruno Romar que asseguraram o acesso a s\u00e9rie ouro, ap\u00f3s terem terminado a disputa da s\u00e9rie prata na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[80,8],"tags":[],"class_list":["post-1108","post","type-post","status-publish","format-standard","hentry","category-estaduais-individuais-2011","category-modalidade-dadinho","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1108"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1108"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1108\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}