{"id":1418,"date":"2010-02-22T21:49:00","date_gmt":"2010-02-23T00:49:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2010\/02\/22\/pastilha-supercopa-marca-inicio-da-temporada-2010-2\/"},"modified":"2010-02-22T21:49:00","modified_gmt":"2010-02-23T00:49:00","slug":"pastilha-supercopa-marca-inicio-da-temporada-2010-2","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2010\/02\/22\/pastilha-supercopa-marca-inicio-da-temporada-2010-2\/","title":{"rendered":"PASTILHA &#8211; SUPERCOPA MARCA IN\u00cdCIO DA TEMPORADA 2010"},"content":{"rendered":"<p><a href=\"http:\/\/2.bp.blogspot.com\/_1yQiVUlBz5Y\/S4MqRGBIjRI\/AAAAAAAAAbc\/WEVeq6OmtY8\/s1600-h\/River.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5441239247955201298\" src=\"http:\/\/2.bp.blogspot.com\/_1yQiVUlBz5Y\/S4MqRGBIjRI\/AAAAAAAAAbc\/WEVeq6OmtY8\/s200\/River.jpg\" style=\"cursor: hand; display: block; height: 150px; margin: 0px auto 10px; text-align: center; width: 200px;\" \/><\/a> <\/p>\n<div><\/div>\n<div>Ser\u00e1 realizada no RIVER F.C, situado na Rua Jo\u00e3o Pinheiro, 426 \u2013 Piedade-RJ, no pr\u00f3ximo dia 28 de fevereiro a partir das 10:00h, a <b>SUPERCOPA<\/b>, primeira competi\u00e7\u00e3o oficial da temporada 2010 na modalidade PASTILHA.<\/div>\n<div><\/div>\n<p><\/p>\n<div>A competi\u00e7\u00e3o contar\u00e1 com a presen\u00e7a de 32 (trinta e dois) atletas e o Vasco ser\u00e1 representado pelo quarteto formado por Carlos &#8220;Bad&#8221; Renato, Igor, Marcelo Lages e Toninho.<\/div>\n<div><\/div>\n<p><\/p>\n<div>Confira os grupos da competi\u00e7\u00e3o com atletas do Vasco.<\/div>\n<div><\/div>\n<p><\/p>\n<div>Grupo C:<\/div>\n<div><\/div>\n<p><\/p>\n<div><b>Marcelo Lages (Vasco)<\/b><\/div>\n<div>\u00c1vila (Portuguesa)<\/div>\n<div>Pablo (Friburguense)<\/div>\n<div>Washigton (Clube dos 500)<\/div>\n<div><\/div>\n<p><\/p>\n<div>Grupo D:<\/div>\n<div><\/div>\n<p><\/p>\n<div><b>Carlos &#8220;Bad&#8221; Renato (Vasco)<\/b><\/div>\n<div>Vinicius (Clube dos 500)<\/div>\n<div>Andr\u00e9 (Portuguesa)<\/div>\n<div>Matheus (Clube dos 500)<\/div>\n<div><\/div>\n<p><\/p>\n<div>Grupo G:<\/div>\n<div><\/div>\n<p><\/p>\n<div><b>Toninho (Vasco)<\/b><\/div>\n<div>Ricardo (Goitac\u00e1z)<\/div>\n<div>Flavio (Fluminense)<\/div>\n<div>Pedr\u00e3o (River)<\/div>\n<div><\/div>\n<p><\/p>\n<div>Grupo H:<\/div>\n<div><\/div>\n<p><\/p>\n<div><b>Igor (Vasco)<\/b><\/div>\n<div>Carlinhos (Clube dos 500)<\/div>\n<div>Marcelinho (Portuguesa)<\/div>\n<div>G. Fialho (Bangu)<\/div>\n<div><\/div>\n<p><\/p>\n<div>Al\u00e9m da competi\u00e7\u00e3o individual, haver\u00e1 a entrega do trof\u00e9u de Campe\u00e3o da <b>SUPERCOPA INTERCLUBES<\/b> ao Vasco. Vale lembrar, que a competi\u00e7\u00e3o seria disputada entre os campe\u00f5es da Copa FEFUMERJ e ESTADUAL, mas o Vasco acabou conquistando os dois t\u00edtulos, assegurando tamb\u00e9m o t\u00edtulo da SUPERCOPA conforme previs\u00e3o do regulamento.<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 realizada no RIVER F.C, situado na Rua Jo\u00e3o Pinheiro, 426 \u2013 Piedade-RJ, no pr\u00f3ximo dia 28 de fevereiro a partir das 10:00h, a SUPERCOPA, primeira competi\u00e7\u00e3o oficial da temporada 2010 na modalidade PASTILHA. A competi\u00e7\u00e3o contar\u00e1 com a presen\u00e7a de 32 (trinta e dois) atletas e o Vasco ser\u00e1 representado pelo quarteto formado por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1418","post","type-post","status-publish","format-standard","hentry","category-modalidade-pastilha","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1418"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1418"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1418\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}