{"id":1495,"date":"2009-10-29T23:18:00","date_gmt":"2009-10-30T01:18:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2009\/10\/29\/vasco-sediara-primeiras-competicoes-nacionais-de-subbuteo\/"},"modified":"2009-10-29T23:18:00","modified_gmt":"2009-10-30T01:18:00","slug":"vasco-sediara-primeiras-competicoes-nacionais-de-subbuteo","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2009\/10\/29\/vasco-sediara-primeiras-competicoes-nacionais-de-subbuteo\/","title":{"rendered":"VASCO SEDIAR\u00c1 PRIMEIRAS COMPETI\u00c7\u00d5ES NACIONAIS DE SUBBUTEO"},"content":{"rendered":"<p><a href=\"http:\/\/2.bp.blogspot.com\/_1yQiVUlBz5Y\/SupOjSO4bdI\/AAAAAAAAARM\/ZYwXW_puSgA\/s1600-h\/logo2.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5398213471453605330\" src=\"http:\/\/2.bp.blogspot.com\/_1yQiVUlBz5Y\/SupOjSO4bdI\/AAAAAAAAARM\/ZYwXW_puSgA\/s200\/logo2.jpg\" style=\"cursor: hand; display: block; height: 176px; margin: 0px auto 10px; text-align: center; width: 200px;\" \/><\/a> O CR Vasco da Gama sediar\u00e1 as primeiras competi\u00e7\u00f5es nacionais de SUBBUTEO, confira abaixo a CARTA CONVITE enviada pela LBS &#8211; Liga Brasileira de Subbuteo.<\/p>\n<div><\/div>\n<div><\/div>\n<p><\/p>\n<div><\/div>\n<p><\/p>\n<div><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5398213840709283410\" src=\"http:\/\/2.bp.blogspot.com\/_1yQiVUlBz5Y\/SupO4x0S7lI\/AAAAAAAAARU\/Q8Hm1yEh3Aw\/s200\/LBS.jpg\" style=\"cursor: hand; display: block; height: 176px; margin: 0px auto 10px; text-align: center; width: 200px;\" \/><br \/>LBS (Liga Brasileira de Subbuteo)<br \/>www.subbuteobrasil.blogger.com.br<\/p>\n<p>Rio de Janeiro, 30 de Outubro de 2009.<\/p>\n<p>I COPA DO BRASIL &amp; I CAMPEONATO BRASILEIRO DE SUBBUTEO<\/p><\/div>\n<div><\/div>\n<p><\/p>\n<div>CARTA CONVITE<\/div>\n<div>Estamos oficializando Convite aos jogadores e clubes para a participa\u00e7\u00e3o na I Copa do Brasil &amp; I Campeonato Brasileiro de Subbuteo, tendo a LBS &#8211; Liga Brasileira de Subbuteo, como organizadora do evento, definido que o mesmo ser\u00e1 realizado na cidade do Rio de Janeiro.<\/div>\n<div><\/div>\n<p><\/p>\n<div>A competi\u00e7\u00e3o ser\u00e1 na sede do Club de Regatas Vasco da Gama, um dos clubes pioneiros e incentivador do Subbuteo no Brasil. <\/div>\n<div><\/div>\n<p><\/p>\n<div>A seguir o cronograma das competi\u00e7\u00f5es:<\/div>\n<div><\/div>\n<p><\/p>\n<div>LOCAL: Club de Regatas Vasco da Gama, Rua Gal. Alm\u00e9rio de Moura, 131, Bairro Vasco da Gama, Rio de Janeiro \u2013 RJ.<\/div>\n<p><\/p>\n<div>DATAS DO EVENTO:<\/div>\n<div><\/div>\n<p><\/p>\n<div>Dias 05 e 06 de dezembro de 2009. <\/div>\n<div><\/div>\n<p><\/p>\n<div>Dia 05:<\/div>\n<p><\/p>\n<div>09:00 horas &#8211; Congresso T\u00e9cnico (Esclarecimentos sobre a regra, demonstra\u00e7\u00f5es, debate sobre futuras competi\u00e7\u00f5es e sorteio dos grupos).<\/div>\n<p><\/p>\n<div>12:45 horas &#8211; Solenidade de Abertura<\/div>\n<p><\/p>\n<div>13:00 horas &#8211; Abertura da Competi\u00e7\u00e3o \u2013 COPA DO BRASIL (sistema de jogos eliminat\u00f3rios, ou seja, o tradicional mata-mata, somente categoria individual) e CAMPEONATO BRASILEIRO (Equipes)*.<\/div>\n<div><\/div>\n<p><\/p>\n<div>Dia 06:<\/div>\n<p><\/p>\n<div>09:30 horas &#8211; In\u00edcio dos jogos (Campeonato Brasileiro Individual).<\/div>\n<div><\/div>\n<p><\/p>\n<div>CATEGORIAS:<\/div>\n<div><\/div>\n<p><\/p>\n<div>INDIVIDUAL e EQUIPES (*Para forma\u00e7\u00e3o da equipe ser\u00e3o necess\u00e1rios ao menos 3 jogadores)<\/p>\n<p>PR\u00caMIOS: Os 4 (quatro) primeiros colocados de cada competi\u00e7\u00e3o receber\u00e3o a seguinte premia\u00e7\u00e3o: Trof\u00e9u de 1\u00ba ao 3\u00ba Lugar e medalha para o 4\u00ba colocado.<\/p><\/div>\n<div>Por se tratar de um marco hist\u00f3rico, ou seja, a realiza\u00e7\u00e3o no Brasil das primeiras competi\u00e7\u00f5es nacionais de Subbuteo, todos os jogadores receber\u00e3o um CERTIFICADO DE PARTICIPA\u00c7\u00c3O.<\/p>\n<p>RANKING NACIONAL: As competi\u00e7\u00f5es pontuar\u00e3o para o ranking nacional a ser utilizado para distribui\u00e7\u00e3o de vagas para o I Campeonato Sul-Americano e para o Mundial, competi\u00e7\u00f5es a serem realizadas em 2010.<\/p><\/div>\n<div>TAXA DE INSCRI\u00c7\u00c3O:R$ 40,00 (Quarenta Reais) com direito a participa\u00e7\u00e3o em todas as competi\u00e7\u00f5es.<\/div>\n<div><\/div>\n<p><\/p>\n<div>Prazo de inscri\u00e7\u00e3o termina no dia 30\/11\/2009.<\/div>\n<div><\/div>\n<p><\/p>\n<div>Os interessados dever\u00e3o enviar sua inscri\u00e7\u00e3o por e-mail, para: <a href=\"mailto:subbuteo.brasil@gmail.com\">subbuteo.brasil@gmail.com<\/a><\/div>\n<div><\/div>\n<p><\/p>\n<div>A solicita\u00e7\u00e3o deve vir preenchida com : Nome Completo, Clube e Cidade (UF), com c\u00f3pia do respectivo recibo de dep\u00f3sito da inscri\u00e7\u00e3o, bem como, solicita\u00e7\u00e3o de cadastro junto \u00e0 Liga Brasileira de Subbuteo.<\/p>\n<p>O jogador dever\u00e1 ainda especificar as competi\u00e7\u00f5es que pretende disputar.<\/p>\n<p>A LBS indicar\u00e1 os atletas que far\u00e3o parte na Comiss\u00e3o de Disciplina caso ela venha a se reunir para julgar alguma ocorr\u00eancia.<\/p><\/div>\n<div><\/div>\n<p><\/p>\n<div>CONTA PARA DEP\u00d3SITO:<\/div>\n<div><\/div>\n<p><\/p>\n<div>Favorecido &gt; Igor Monteiro Quintaes (Tesoureiro &#8211; LBS \u2013 Liga Brasileira de Subbuteo)<br \/>Banco Bradesco<br \/>Ag\u00eancia n\u00ba 0212<br \/>Conta poupan\u00e7a n\u00ba 0112833-7<\/p>\n<p>HOT\u00c9IS<\/p><\/div>\n<div><\/div>\n<p><\/p>\n<div>FORMULE 1<\/div>\n<p><\/p>\n<div><a href=\"http:\/\/www.accorhotels.com.br\/guiahoteis\/formule1\/hotel_main.asp?cd_hotel=200\" target=\"_blank\" rel=\"noopener\">http:\/\/www.accorhotels.com.br\/guiahoteis\/formule1\/hotel_main.asp?cd_hotel=200<\/a><\/div>\n<p><\/p>\n<div>Op\u00e7\u00e3o mais barata da cadeia ACCOR, apartamento para no m\u00e1ximo 3 pessoas, sendo que existem 2 camas: 1 de casal e uma de solteiro. Caf\u00e9 da manha cobrado \u00e0 parte.<\/div>\n<div><\/div>\n<p><\/p>\n<div>IBIS<\/div>\n<p><\/p>\n<div><a href=\"http:\/\/www.accorhotels.com.br\/guiahoteis\/ibis\/hotel_main.asp?cd_hotel=201\" target=\"_blank\" rel=\"noopener\">http:\/\/www.accorhotels.com.br\/guiahoteis\/ibis\/hotel_main.asp?cd_hotel=201<\/a><\/div>\n<p><\/p>\n<div>Op\u00e7\u00e3o intermediaria para at\u00e9 2 pessoas. Caf\u00e9 da manha cobrado \u00e0 parte. Existe uma tarifa chamada VITABIS, apenas para fins de semana, para pessoas que venham disputar competi\u00e7\u00f5es esportivas:<\/div>\n<p><\/p>\n<div><a href=\"http:\/\/www.accorhotels.com.br\/ibis\/pt\/prog_vitabis.asp\" target=\"_blank\" rel=\"noopener\">http:\/\/www.accorhotels.com.br\/ibis\/pt\/prog_vitabis.asp<\/a><\/div>\n<div><\/div>\n<p><\/p>\n<div>Para os dois hot\u00e9is: (um do lado do outro)- Existe um estacionamento, terceirizado. &#8211; Ponto de taxi na porta.<\/p>\n<p>Atenciosamente,<\/p>\n<p>LBS \u2013 Liga Brasileira de Subbuteo<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O CR Vasco da Gama sediar\u00e1 as primeiras competi\u00e7\u00f5es nacionais de SUBBUTEO, confira abaixo a CARTA CONVITE enviada pela LBS &#8211; Liga Brasileira de Subbuteo. LBS (Liga Brasileira de Subbuteo)www.subbuteobrasil.blogger.com.br Rio de Janeiro, 30 de Outubro de 2009. I COPA DO BRASIL &amp; I CAMPEONATO BRASILEIRO DE SUBBUTEO CARTA CONVITE Estamos oficializando Convite aos jogadores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[4,99,101],"tags":[],"class_list":["post-1495","post","type-post","status-publish","format-standard","hentry","category-modalidade-subbuteo","category-nacionais-de-clubes-2009","category-nacionais-individuais-2009","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1495"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}