{"id":1756,"date":"2008-08-19T15:41:00","date_gmt":"2008-08-19T18:41:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2008\/08\/19\/"},"modified":"2008-08-19T15:41:00","modified_gmt":"2008-08-19T18:41:00","slug":"1756","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2008\/08\/19\/1756\/","title":{"rendered":""},"content":{"rendered":"<p><img decoding=\"async\" alt=\"\" border=\"0\" src=\"http:\/\/www.crvascodagama.com\/fotos_noticia\/400\/Copa_FEFUMERJ_2008_004.jpg\" style=\"cursor: hand; float: left; margin: 0px 10px 10px 0px; width: 200px;\" \/><span style=\"font-family: arial;\"><b>07\/07 &#8211; Futmesa do Vasco conquista primeiro t\u00edtulo da gest\u00e3o Roberto Dinamite<\/b><\/span><span style=\"font-family: arial;\">A equipe de futebol de mesa do Vasco da modalidade 12 toques conquistou no \u00faltimo s\u00e1bado (05\/07) o primeiro t\u00edtulo do clube na gest\u00e3o do Presidente Carlos Roberto Dinamite de Oliveira, ao faturar o tetracampeonato invicto da Copa FEFUMERJ na categoria master, competi\u00e7\u00e3o disputada na AABB Tijuca.<\/span><span style=\"font-family: Arial;\">O time da casa foi o primeiro advers\u00e1rio do Vasco, que venceu por 48&#215;0. Na seq\u00fc\u00eancia, o Gigante da Colina venceu o Fluminense por 36&#215;9. No outro grupo, o Am\u00e9rica venceu Flamengo e Petropolitano e se classificou para a final.<\/span><span style=\"font-family: Arial;\">As duas equipes, que disputam em 2008 a hegemonia do futebol de mesa carioca, j\u00e1 que ambas conquistaram tr\u00eas vezes o campeonato estadual de clubes, fizeram pela quarta vez uma final de campeonato e em todas, o Vasco saiu vencedor. Foi assim nos estaduais de 2003, 2006 e 2007. Na final da Copa FEFMERJ, a equipe vasca\u00edna venceu por 35&#215;11 com parciais de 7&#215;4 \/ 12&#215;0 \/ 4&#215;7 e 12&#215;0.<\/span><span style=\"font-family: Arial;\">O quarteto vasca\u00edno atuou em todas partidas e pontuou com:<\/span><span style=\"font-family: Arial;\">Geraldo Ramos &#8211; 11 vit\u00f3rias, 1 derrota, 33 pontos<\/span><span style=\"font-family: Arial;\">Marcelo Lages &#8211; 10 vit\u00f3rias, 2 derrotas, 30 pontos<\/span><span style=\"font-family: Arial;\">Dudu &#8211; 9 vit\u00f3rias, 2 empates e 1 derrota, 29 pontos<\/span><span style=\"font-family: Arial;\">Rodolfo Jos\u00e9 &#8211; 8 vit\u00f3rias, 3 empates e 1 derrota, 27 pontos<\/span><span style=\"font-family: Arial;\">Essa foi a quarta edi\u00e7\u00e3o da competi\u00e7\u00e3o, que era disputada de dois em dois anos e a partir desse ano, passou a integrar o calend\u00e1rio oficial da modalidade de forma anual.<\/span><span style=\"font-family: Arial;\">Fonte: <a href=\"http:\/\/www.crvascodagama.com\/\">Site Oficial do Vasco da Gama<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>07\/07 &#8211; Futmesa do Vasco conquista primeiro t\u00edtulo da gest\u00e3o Roberto DinamiteA equipe de futebol de mesa do Vasco da modalidade 12 toques conquistou no \u00faltimo s\u00e1bado (05\/07) o primeiro t\u00edtulo do clube na gest\u00e3o do Presidente Carlos Roberto Dinamite de Oliveira, ao faturar o tetracampeonato invicto da Copa FEFUMERJ na categoria master, competi\u00e7\u00e3o disputada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1756","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1756"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1756"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1756\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}