{"id":26,"date":"2019-10-30T14:52:00","date_gmt":"2019-10-30T17:52:00","guid":{"rendered":""},"modified":"2022-07-23T07:58:16","modified_gmt":"2022-07-23T10:58:16","slug":"3-toques-eder-e-bronze-no-estadual-individual-2019","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2019\/10\/30\/3-toques-eder-e-bronze-no-estadual-individual-2019\/","title":{"rendered":"3 TOQUES: \u00c9DER \u00c9 BRONZE NO ESTADUAL INDIVIDUAL 2019"},"content":{"rendered":"<\/p>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEgbce9sxQHO8BxYPL2t1Fo_1ZrbyIL9c7u7owx0mLCIjjas0jTkRAvBSOsdj_UCfq0U85gaoDaKZX5EmfjN--dDfQwyO5n6ZsZBF2-9H4KAWxbOdAhN2-8s8PIivD_TrTym-dzqQrqVjSGhVuuTU72IySMimTROhFlvLf_yLaDMPf5Wlk-5A84X3Hiihg\/s800\/2019_bola3toques_estadual_individual_ouro.webp\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" data-original-height=\"450\" data-original-width=\"800\" height=\"225\" src=\"https:\/\/futmesavasco.com.br\/wp-content\/uploads\/2019\/10\/2019_bola3toques_estadual_individual_ouro-1-300x169.jpg\" width=\"400\" \/><\/a><\/div>\n<p><span style=\"background-color: white; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px;\"><br \/><\/span><\/p>\n<p><span style=\"background-color: white; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px;\"><br \/><\/span><\/p>\n<p><span style=\"background-color: white; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px;\">No \u00faltimo final de semana (26 e 27\/10\/2019) foi realizado nas depend\u00eancias do Departamento de Futebol de Mesa do Club de Regatas Vasco da Gama o<\/span><span style=\"background-color: white; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px;\">&nbsp;<\/span><strong style=\"border: 0px; box-sizing: border-box; color: #444444; font-family: inherit; font-size: 16px; font-stretch: inherit; font-style: inherit; font-variant: inherit; line-height: inherit; margin: 0px; outline: 0px; padding: 0px; vertical-align: baseline;\">XXXVII Campeonato Estadual Individual da Modalidade Bola 3 Toques<\/strong><span style=\"background-color: white; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px;\">.<\/span><\/p>\n<p style=\"background-color: white; border: 0px; box-sizing: border-box; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px; font-stretch: inherit; font-variant-east-asian: inherit; font-variant-numeric: inherit; line-height: 1.6; margin: 0px 0px 15px; outline: 0px; padding: 0px; vertical-align: baseline;\">No s\u00e1bado ocorreu a fase classificat\u00f3ria da competi\u00e7\u00e3o com destaque para os botonistas alvinegros Elinto Pires (atual campe\u00e3o) e Diego Am\u00e9rico. J\u00e1 no domingo, os oito atletas classificados para a s\u00e9rie ouro foram divididos em dois grupos. No primeiro grupo, Elinto Pires obteve o primeiro posto, seguido por <b>\u00c9der Patroc\u00ednio (CRVG)<\/b>. Foram desclassificados nesta fase <b>Jos\u00e9 Ricardo Lage (CRVG)<\/b> e Marcelo Coutinho (BAC).<\/p>\n<p style=\"background-color: white; border: 0px; box-sizing: border-box; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px; font-stretch: inherit; font-variant-east-asian: inherit; font-variant-numeric: inherit; line-height: 1.6; margin: 0px 0px 15px; outline: 0px; padding: 0px; vertical-align: baseline;\">No segundo grupo da segunda fase do campeonato, os dois atletas do Botafogo F.R. conseguiram as vagas para as semifinais. Diego Am\u00e9rico foi o primeiro do grupo, seguido por Bruno Machado. Ainda integraram o grupo dois botonistas do Clube dos 500, Cl\u00e1udio Figueiredo e Luiz Francisco.<\/p>\n<p style=\"background-color: white; border: 0px; box-sizing: border-box; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px; font-stretch: inherit; font-variant-east-asian: inherit; font-variant-numeric: inherit; line-height: 1.6; margin: 0px 0px 15px; outline: 0px; padding: 0px; vertical-align: baseline;\">Pelas semifinais, a dupla Elinto e Diego contava com a vantagem do empate. Em um jogo com chances para ambos os lados, Elinto superou Bruno Machado por 2 a 0, credenciando-se \u00e0 final\u00edssima com a melhor campanha da competi\u00e7\u00e3o, logo com a vantagem da empate na final. Na outra semifinal, Diego venceu <b>\u00c9der Patroc\u00ednio, que fechou sua participa\u00e7\u00e3o como 3\u00ba lugar!<\/b><\/p>\n<p style=\"background-color: white; border: 0px; box-sizing: border-box; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px; font-stretch: inherit; font-variant-east-asian: inherit; font-variant-numeric: inherit; line-height: 1.6; margin: 0px 0px 15px; outline: 0px; padding: 0px; vertical-align: baseline;\">Deste modo, formou-se a final de atletas integrantes do Botafogo F.R.: Elinto Pires X Diego Am\u00e9rico.<\/p>\n<p style=\"background-color: white; border: 0px; box-sizing: border-box; color: #444444; font-family: &quot;Open Sans&quot;, serif; font-size: 16px; font-stretch: inherit; font-variant-east-asian: inherit; font-variant-numeric: inherit; line-height: 1.6; margin: 0px 0px 15px; outline: 0px; padding: 0px; vertical-align: baseline;\">Apesar de contar com a vantagem do empate, em um jogo extremamente tenso e equilibrado,&nbsp;<span style=\"border: 0px; box-sizing: border-box; font-family: inherit; font-stretch: inherit; font-style: inherit; font-variant: inherit; line-height: inherit; margin: 0px; outline: 0px; padding: 0px; vertical-align: baseline;\">Diego Am\u00e9rico<\/span>&nbsp;demonstrou mais sangue frio, vencendo Elinto por 2 a 0 e sagrando-se, pela segunda vez, campe\u00e3o estadual da modalidade.<\/p>\n<p>Agora os botonistas do nosso Estado intensificar\u00e3o os treinamentos, visando ao Campeonato Brasileiro Interclubes, que ser\u00e1 realizado na cidade de Bras\u00edlia, nos dias 15, 16 e 17\/11\/19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo final de semana (26 e 27\/10\/2019) foi realizado nas depend\u00eancias do Departamento de Futebol de Mesa do Club de Regatas Vasco da Gama o&nbsp;XXXVII Campeonato Estadual Individual da Modalidade Bola 3 Toques. No s\u00e1bado ocorreu a fase classificat\u00f3ria da competi\u00e7\u00e3o com destaque para os botonistas alvinegros Elinto Pires (atual campe\u00e3o) e Diego Am\u00e9rico. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","entry","has-media"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":2,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"predecessor-version":[{"id":1827,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26\/revisions\/1827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media\/1825"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}