{"id":2639,"date":"2025-05-18T19:15:00","date_gmt":"2025-05-18T22:15:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/?p=2639"},"modified":"2025-06-16T12:03:43","modified_gmt":"2025-06-16T15:03:43","slug":"12-toques-thiago-pennaconquista-a-copa-manoel-gomes-tubino","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2025\/05\/18\/12-toques-thiago-pennaconquista-a-copa-manoel-gomes-tubino\/","title":{"rendered":"12 TOQUES: THIAGO PENNA CONQUISTA ETAPA DO ESTADUAL INDIVIDUAL"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Neste domingo, 18 de maio, foi a vez da categoria adulto disputar a 3\u00aa Etapa do Campeonato Estadual Individual de Futebol de Mesa \u2013 Regra 12 Toques, promovida pela FEFUMERJ. A competi\u00e7\u00e3o, realizada na sede do Botafogo Futmesa, no Centro do Rio de Janeiro, levou o nome de Copa Manoel Gomes Tubino, em homenagem \u00e1quele que oficializou o Futebol de Mesa como esporte no Brasil em 1988.<\/p>\n\n\n\n<p>Com confrontos muito equilibrados ao longo do dia, o destaque ficou por conta do vasca\u00edno Thiago Penna, que sagrou-se campe\u00e3o ao superar Marcus Vinicius, do Fluminense, na final. Marcelinho Dias(America) garantiu a terceira coloca\u00e7\u00e3o, enquanto o tricolor Marcos Antunes completou o p\u00f3dio com o quarto lugar.<\/p>\n\n\n\n<p>Na S\u00e9rie Prata, destinada aos atletas que n\u00e3o avan\u00e7aram \u00e0 fase principal, o t\u00edtulo ficou com o atleta rubro, Ramos, que superou Marco Ant\u00f4nio, do Vasco da Gama, em uma final disputada entre dois atletas com idade para a categoria Master. Na decis\u00e3o do terceiro lugar, Jo\u00e3o Victor, do Petropolitano, levou a melhor sobre Rodrigo Ad\u00e3o, do America.<\/p>\n\n\n\n<p>A etapa foi marcada por disputas equilibradas e pela participa\u00e7\u00e3o de representantes de diversos clubes tradicionais do estado, como America, Botafogo, Flamengo, Fluminense, Friburguense, Petropolitano e Vasco da Gama, reafirmando a for\u00e7a e a tradi\u00e7\u00e3o do Futebol de Mesa fluminense.<\/p>\n\n\n\n<p>A pr\u00f3xima Etapa acontece nos dias 12 e 13 de julho no Friburguense Atl\u00e9tico Clube, na regi\u00e3o serrana do Rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo, 18 de maio, foi a vez da categoria adulto disputar a 3\u00aa Etapa do Campeonato Estadual Individual de Futebol de Mesa \u2013 Regra 12 Toques, promovida pela FEFUMERJ. A competi\u00e7\u00e3o, realizada na sede do Botafogo Futmesa, no Centro do Rio de Janeiro, levou o nome de Copa Manoel Gomes Tubino, em homenagem \u00e1quele [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","entry","has-media"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2639"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2639"}],"version-history":[{"count":3,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2639\/revisions"}],"predecessor-version":[{"id":2646,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2639\/revisions\/2646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media\/2642"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}