{"id":2677,"date":"2025-08-23T16:41:00","date_gmt":"2025-08-23T19:41:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/?p=2677"},"modified":"2025-09-01T16:45:46","modified_gmt":"2025-09-01T19:45:46","slug":"12-toques-evandro-gomes-e-campeao-da-5a-etapa-master","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2025\/08\/23\/12-toques-evandro-gomes-e-campeao-da-5a-etapa-master\/","title":{"rendered":"12 TOQUES: EVANDRO GOMES \u00c9 CAMPE\u00c3O DA 5\u00aa ETAPA MASTER"},"content":{"rendered":"\n<p>O Vasco Futmesa brilhou na disputa da categoria Master (48+) da 5\u00aa Etapa do Campeonato Estadual Individual de Futebol de Mesa \u2013 Regra 12 Toques, realizada neste s\u00e1bado (23) na sede do Botafogo Futmesa, no Centro do Rio.<\/p>\n\n\n\n<p>Na competi\u00e7\u00e3o organizada pela Federa\u00e7\u00e3o de Futebol de Mesa do Estado do Rio de Janeiro (FEFUMERJ), o grande destaque foi o vasca\u00edno Evandro Gomes, que confirmou sua \u00f3tima fase e conquistou o t\u00edtulo da S\u00e9rie Ouro ao derrotar na final o rubro-negro Vinicius Mendes (Flamengo) por 7 a 4, garantindo o trof\u00e9u para o Gigante da Colina.<\/p>\n\n\n\n<p>O Vasco ainda emplacou mais um representante no p\u00f3dio: Moacir, que superou Nelson Joazeiro (Fluminense) na disputa pelo 3\u00ba lugar, confirmando a for\u00e7a cruzmaltina na competi\u00e7\u00e3o.<\/p>\n\n\n\n<p>\ud83c\udfc6 P\u00f3dio da S\u00e9rie Ouro \u2013 Categoria Master (5\u00aa Etapa)<br>\ud83e\udd47 Evandro Gomes (Vasco da Gama)<br>\ud83e\udd48 Vinicius Mendes (Flamengo)<br>\ud83e\udd49 Moacir (Vasco da Gama)<br>4\u00ba Nelson Joazeiro (Fluminense)<br><br><\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/futmesavasco.com.br\/wp-content\/uploads\/2025\/09\/2025_12toques_estadual_individual_master_etapa5_campeao.png\" alt=\"\" class=\"wp-image-2679\" srcset=\"https:\/\/futmesavasco.com.br\/wp-content\/uploads\/2025\/09\/2025_12toques_estadual_individual_master_etapa5_campeao.png 600w, https:\/\/futmesavasco.com.br\/wp-content\/uploads\/2025\/09\/2025_12toques_estadual_individual_master_etapa5_campeao-300x300.png 300w, https:\/\/futmesavasco.com.br\/wp-content\/uploads\/2025\/09\/2025_12toques_estadual_individual_master_etapa5_campeao-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Com o resultado, Evandro segue firme na lideran\u00e7a do ranking estadual Master (48+). Amanh\u00e3 (24\/8) \u00e9 a vez da categoria adulto.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Vasco Futmesa brilhou na disputa da categoria Master (48+) da 5\u00aa Etapa do Campeonato Estadual Individual de Futebol de Mesa \u2013 Regra 12 Toques, realizada neste s\u00e1bado (23) na sede do Botafogo Futmesa, no Centro do Rio. Na competi\u00e7\u00e3o organizada pela Federa\u00e7\u00e3o de Futebol de Mesa do Estado do Rio de Janeiro (FEFUMERJ), o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","entry","has-media"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2677"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2677"}],"version-history":[{"count":1,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2677\/revisions"}],"predecessor-version":[{"id":2680,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2677\/revisions\/2680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media\/2678"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}