{"id":31,"date":"2018-11-08T15:27:00","date_gmt":"2018-11-08T17:27:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2018\/11\/08\/vasco-vai-em-busca-do-bicampeonato-mundial-de-futmesa\/"},"modified":"2018-11-08T15:27:00","modified_gmt":"2018-11-08T17:27:00","slug":"vasco-vai-em-busca-do-bicampeonato-mundial-de-futmesa","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2018\/11\/08\/vasco-vai-em-busca-do-bicampeonato-mundial-de-futmesa\/","title":{"rendered":"VASCO VAI EM BUSCA DO BICAMPEONATO MUNDIAL DE FUTMESA"},"content":{"rendered":"<p><\/p>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-o2CUdAK4fNg\/W-R_nQQCKpI\/AAAAAAAAI_U\/53HN6B3sjsUz59XbFsH5BT90OWTZM3hJwCLcBGAs\/s1600\/IMG-20181022-WA0074.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" data-original-height=\"900\" data-original-width=\"750\" height=\"400\" src=\"https:\/\/1.bp.blogspot.com\/-o2CUdAK4fNg\/W-R_nQQCKpI\/AAAAAAAAI_U\/53HN6B3sjsUz59XbFsH5BT90OWTZM3hJwCLcBGAs\/s400\/IMG-20181022-WA0074.jpg\" width=\"332\" \/><\/a><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\">O Est\u00e1dio do Restelo, do Clube de Futebol Os Belenenses, em Lisboa, Portugal, ser\u00e1 sede do Campeonato Mundial de Futebol de Mesa entre os dias 15 e 18 de novembro deste ano.<o:p><\/o:p><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\">A competi\u00e7\u00e3o ser\u00e1 disputada em duas modalidades: sectorball, de origem h\u00fangara e bola 12 toques, de origem brasileira. S\u00e3o as duas regras internacionais reconhecidas do esporte, al\u00e9m do Subbuteo, que possui as suas competi\u00e7\u00f5es organizadas pela FISTF &#8211; Federation of International Sports Table Football e o Mundial \u00e9 disputado em data separada.<o:p><\/o:p><\/p>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/2.bp.blogspot.com\/-jU3KubGsqCE\/Wh3cjENSDVI\/AAAAAAAAIwk\/-q8FZsVaQFMEmI2g84ryOMZUa9qYD-vRQCPcBGAYYCw\/s1600\/mundial_portugal_01c_horiz.png\" style=\"margin-left: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"595\" data-original-width=\"842\" height=\"282\" src=\"https:\/\/2.bp.blogspot.com\/-jU3KubGsqCE\/Wh3cjENSDVI\/AAAAAAAAIwk\/-q8FZsVaQFMEmI2g84ryOMZUa9qYD-vRQCPcBGAYYCw\/s400\/mundial_portugal_01c_horiz.png\" width=\"400\" \/><\/a><\/div>\n<div style=\"clear: both; text-align: center;\"><b>Logo oficial da competi\u00e7\u00e3o.<\/b><\/div>\n<p><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\">Ser\u00e3o tr\u00eas disputas em ambas as modalidades: competi\u00e7\u00e3o individual, de sele\u00e7\u00f5es e interclubes. Os pa\u00edses confirmados s\u00e3o: Brasil, Espanha, Hungria, It\u00e1lia, Jap\u00e3o, Pol\u00f4nia, Portugal e Rom\u00eania. <o:p><\/o:p><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\">Na disputa Interclubes da modalidade 12 toques estar\u00e3o os seguintes times: Palmeiras &#8211; Brasil (campe\u00e3o sul-americano 2017 e atual campe\u00e3o mundial), <b style=\"mso-bidi-font-weight: normal;\">Vasco da Gama \u2013 Brasil<\/b> (campe\u00e3o sul-americano 2016), Debrecen &#8211; Hungria (campe\u00e3o europeu 2016-2017) e o anfitri\u00e3o Belenenses &#8211; Portugal. A equipe vasca\u00edna, Campe\u00e3 Mundial em 2014, em Budapeste, na Hungria, vai em busca do bicampeonato e ser\u00e1 formada pelos seguintes atletas: Dudu, Ednilson, Igor, Marcelo Lages, Moraes, Nando, Renato, Rodolfo e Victor.<o:p><\/o:p><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\">J\u00e1 na competi\u00e7\u00e3o Interclubes da modalidade sectorball, a disputa ser\u00e1 entre o Testv\u00e9ris\u00e9g&nbsp;SE Budapest \u2013 Hungria (campe\u00e3o europeu 2017) e o <b style=\"mso-bidi-font-weight: normal;\">Vasco da Gama \u2013 Brasil<\/b> (campe\u00e3o sul-americano 2017).<o:p><\/o:p><\/div>\n<div style=\"text-align: justify; text-indent: 35.4pt;\"><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\"><span style=\"line-height: 107%;\"><span style=\"font-size: large;\">Galeria de Campe\u00f5es<\/span><span style=\"font-size: 12pt;\"><o:p><\/o:p><\/span><\/span><\/b><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\"><span style=\"line-height: 107%;\"><span style=\"font-size: large;\"><br \/><\/span><\/span><\/b><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\"><span style=\"font-size: 12.0pt; line-height: 107%; mso-bidi-font-size: 11.0pt;\"><br \/><\/span><\/b><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\">Campe\u00f5es &#8211; Competi\u00e7\u00e3o Interclubes<o:p><\/o:p><\/b><\/div>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-collapse: collapse; border: none; mso-border-alt: solid windowtext .5pt; mso-padding-alt: 0cm 5.4pt 0cm 5.4pt; mso-yfti-tbllook: 1184; width: 0px;\">\n<tbody>\n<tr style=\"mso-yfti-firstrow: yes; mso-yfti-irow: 0;\">\n<td style=\"border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 34.55pt;\" valign=\"top\" width=\"46\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Ano<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.95pt;\" valign=\"top\" width=\"143\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Sede<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.5pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">12 Toques<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 127.6pt;\" valign=\"top\" width=\"170\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Sectorball<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 1;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 34.55pt;\" valign=\"top\" width=\"46\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2014<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.95pt;\" valign=\"top\" width=\"143\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Budapeste, Hungria<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.5pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Vasco da Gama \u2013 Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 127.6pt;\" valign=\"top\" width=\"170\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Testv\u00e9ris\u00e9g&nbsp;SE &#8211; Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 2; mso-yfti-lastrow: yes;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 34.55pt;\" valign=\"top\" width=\"46\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2016<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.95pt;\" valign=\"top\" width=\"143\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Rio de Janeiro, Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.5pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Palmeiras \u2013 Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 127.6pt;\" valign=\"top\" width=\"170\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Testv\u00e9ris\u00e9g&nbsp;SE &#8211; Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\"><br \/><\/b><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\">Campe\u00f5es &#8211; Competi\u00e7\u00e3o Individual<o:p><\/o:p><\/b><\/div>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-collapse: collapse; border: none; mso-border-alt: solid windowtext .5pt; mso-padding-alt: 0cm 5.4pt 0cm 5.4pt; mso-yfti-tbllook: 1184; width: 0px;\">\n<tbody>\n<tr style=\"mso-yfti-firstrow: yes; mso-yfti-irow: 0;\">\n<td style=\"border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 35.2pt;\" valign=\"top\" width=\"47\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Ano<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.3pt;\" valign=\"top\" width=\"142\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Sede<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 4.0cm;\" valign=\"top\" width=\"151\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">12 Toques<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.55pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Sectorball<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 1;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 35.2pt;\" valign=\"top\" width=\"47\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2009<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.3pt;\" valign=\"top\" width=\"142\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Budapeste, Hungria<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 4.0cm;\" valign=\"top\" width=\"151\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Quinho Zuccato &#8211; Palmeiras (SP &#8211; Brasil)<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.55pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\"><span style=\"background: white; color: #222222; font-family: &quot;arial&quot; , sans-serif; font-size: 10.5pt;\">Seremet Szil\u00e1rd<\/span>  &#8211; Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 2;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 35.2pt;\" valign=\"top\" width=\"47\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2012<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.3pt;\" valign=\"top\" width=\"142\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Rio de Janeiro, Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 4.0cm;\" valign=\"top\" width=\"151\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Rog\u00e9rio Nascimento \u2013 Curitibano (PR &#8211; Brasil)<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.55pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\"><span style=\"background: white; color: #222222; font-family: &quot;arial&quot; , sans-serif; font-size: 10.5pt;\">Szendrey Tibor<\/span>  &#8211; Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 3; mso-yfti-lastrow: yes;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 35.2pt;\" valign=\"top\" width=\"47\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2015<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 106.3pt;\" valign=\"top\" width=\"142\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Debrecen, Hungria<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 4.0cm;\" valign=\"top\" width=\"151\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Jefferson Genta &#8211; Palmeiras (SP &#8211; Brasil)<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.55pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">J\u00e1nos Koczor &#8211; Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\"><br \/><\/b><\/div>\n<div align=\"center\" style=\"text-align: center; text-indent: 35.4pt;\"><b style=\"mso-bidi-font-weight: normal;\">Campe\u00f5es &#8211; Competi\u00e7\u00e3o de Sele\u00e7\u00f5es<o:p><\/o:p><\/b><\/div>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-collapse: collapse; border: none; mso-border-alt: solid windowtext .5pt; mso-padding-alt: 0cm 5.4pt 0cm 5.4pt; mso-yfti-tbllook: 1184; width: 0px;\">\n<tbody>\n<tr style=\"mso-yfti-firstrow: yes; mso-yfti-irow: 0;\">\n<td style=\"border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 49.4pt;\" valign=\"top\" width=\"66\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Ano<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.45pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Sede<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">12 Toques<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-left: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Sectorball<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 1;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 49.4pt;\" valign=\"top\" width=\"66\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2009<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.45pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Budapeste, Hungria<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 2;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 49.4pt;\" valign=\"top\" width=\"66\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2012<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.45pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Rio de Janeiro, Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Hungria<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 3; mso-yfti-lastrow: yes;\">\n<td style=\"border-top: none; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 49.4pt;\" valign=\"top\" width=\"66\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">2015<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 120.45pt;\" valign=\"top\" width=\"161\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Debrecen, Hungria<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Brasil<o:p><\/o:p><\/div>\n<\/td>\n<td style=\"border-bottom: solid windowtext 1.0pt; border-left: none; border-right: solid windowtext 1.0pt; border-top: none; mso-border-alt: solid windowtext .5pt; mso-border-left-alt: solid windowtext .5pt; mso-border-top-alt: solid windowtext .5pt; padding: 0cm 5.4pt 0cm 5.4pt; width: 92.15pt;\" valign=\"top\" width=\"123\">\n<div align=\"center\" style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; text-align: center;\">Rom\u00eania<o:p><\/o:p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/4.bp.blogspot.com\/-M5SIEUi_x0w\/W-R__wXM7bI\/AAAAAAAAI_c\/XZoPnmmlzO8rFIW7E8uFz6iAM4mZrUKYACLcBGAs\/s1600\/20180612-225525-1-.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"926\" data-original-width=\"960\" height=\"385\" src=\"https:\/\/4.bp.blogspot.com\/-M5SIEUi_x0w\/W-R__wXM7bI\/AAAAAAAAI_c\/XZoPnmmlzO8rFIW7E8uFz6iAM4mZrUKYACLcBGAs\/s400\/20180612-225525-1-.jpg\" width=\"400\" \/><\/a><\/div>\n<div style=\"clear: both; text-align: center;\"><b>VASCO CAMPE\u00c3O MUNDIAL INTERCLUBES 2014!<\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><b><br \/><\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-aictFwoyLls\/W-SEyGC35II\/AAAAAAAAJAE\/SwOR1ZiltQgSIHw-o09q9xdb6g8ZAG9iACLcBGAs\/s1600\/SDC10470.JPG\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" height=\"300\" src=\"https:\/\/1.bp.blogspot.com\/-aictFwoyLls\/W-SEyGC35II\/AAAAAAAAJAE\/SwOR1ZiltQgSIHw-o09q9xdb6g8ZAG9iACLcBGAs\/s400\/SDC10470.JPG\" width=\"400\" \/><\/a><\/div>\n<div style=\"clear: both; text-align: center;\"><b>Marcelo Lages e Renato. Vasca\u00ednos campe\u00f5es Mundiais pela Sele\u00e7\u00e3o em 2009!<\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><b><br \/><\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-TSSIbGi9xRE\/W-SD2yA46MI\/AAAAAAAAI_0\/WSZvVLS-WQcxn5qwRcS7N1qlo4Sbi2gaACLcBGAs\/s1600\/P%25C3%25B3dios%2B%252820%2529.JPG\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" height=\"300\" src=\"https:\/\/1.bp.blogspot.com\/-TSSIbGi9xRE\/W-SD2yA46MI\/AAAAAAAAI_0\/WSZvVLS-WQcxn5qwRcS7N1qlo4Sbi2gaACLcBGAs\/s400\/P%25C3%25B3dios%2B%252820%2529.JPG\" width=\"400\" \/><\/a><\/div>\n<div style=\"clear: both; text-align: center;\">Marcelo Lages e Rhaniery.&nbsp;<b>Vasca\u00ednos campe\u00f5es Mundiais pela Sele\u00e7\u00e3o em 2012!<\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><b><br \/><\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/4.bp.blogspot.com\/-WgYk9bUKIDI\/W-SEbSO6LgI\/AAAAAAAAI_8\/OY8Gi4hW98AuEEwjMc4BM_LBK2uZvbw0ACLcBGAs\/s1600\/2015_bola12toques_mundial_30.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"375\" data-original-width=\"720\" height=\"207\" src=\"https:\/\/4.bp.blogspot.com\/-WgYk9bUKIDI\/W-SEbSO6LgI\/AAAAAAAAI_8\/OY8Gi4hW98AuEEwjMc4BM_LBK2uZvbw0ACLcBGAs\/s400\/2015_bola12toques_mundial_30.jpg\" width=\"400\" \/><\/a><\/div>\n<div style=\"clear: both; text-align: center;\">Marcelo Lages,&nbsp;<b>campe\u00e3o Mundial pela Sele\u00e7\u00e3o em 2015!<\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><b><br \/><\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><b><br \/><\/b><\/div>\n<div style=\"clear: both; text-align: center;\"><b><br \/><\/b><\/div>\n<div align=\"center\"><\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Est\u00e1dio do Restelo, do Clube de Futebol Os Belenenses, em Lisboa, Portugal, ser\u00e1 sede do Campeonato Mundial de Futebol de Mesa entre os dias 15 e 18 de novembro deste ano. A competi\u00e7\u00e3o ser\u00e1 disputada em duas modalidades: sectorball, de origem h\u00fangara e bola 12 toques, de origem brasileira. S\u00e3o as duas regras internacionais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}