{"id":610,"date":"2013-10-28T14:01:00","date_gmt":"2013-10-28T16:01:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2013\/10\/28\/ramos-e-podio-no-estadual-individual-modalidade-bola-12-toques\/"},"modified":"2013-10-28T14:01:00","modified_gmt":"2013-10-28T16:01:00","slug":"ramos-e-podio-no-estadual-individual-modalidade-bola-12-toques","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2013\/10\/28\/ramos-e-podio-no-estadual-individual-modalidade-bola-12-toques\/","title":{"rendered":"RAMOS \u00c9 P\u00d3DIO NO ESTADUAL INDIVIDUAL &#8211; MODALIDADE BOLA 12 TOQUES"},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/3.bp.blogspot.com\/-EHblgpZHR40\/Um6W5LijBEI\/AAAAAAAAEDA\/Ff_U4Zb7S20\/s1600\/Ramos+-+6%C2%AA+etapa.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"240\" src=\"http:\/\/3.bp.blogspot.com\/-EHblgpZHR40\/Um6W5LijBEI\/AAAAAAAAEDA\/Ff_U4Zb7S20\/s320\/Ramos+-+6%C2%AA+etapa.jpg\" width=\"320\" \/><\/a><\/div>\n<p><\/p>\n<div style=\"text-align: justify;\">Foi realizada neste \u00faltimo final de semana, 26 e 27\/10, na AABB-Tijuca, a \u00faltima etapa do estadual individual da modalidade Bola 12 Toques.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ramos do CRVG terminou a etapa na 2\u00aa coloca\u00e7\u00e3o, assegurando assim a 3\u00aa coloca\u00e7\u00e3o do Estadual Individual 2013. Destaque ainda para Rodolfo (CRVG) que terminou o estadual na 4\u00aa coloca\u00e7\u00e3o. Armando do Fluminense foi o campe\u00e3o da temporada e Argolo do Flamengo ficou com o vice-campeonato.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Rodrigo Pedreira do America-RJ foi o campe\u00e3o da categoria Adulto, superando seus companheiros de equipe, Bira que ficou com o vice-campeonato e Lucas com a 3\u00aa coloca\u00e7\u00e3o.<\/p>\n<p>Pela primeira vez, em 10 (dez) anos, o CR Vasco da Gama deixou de conquistar o estadual individual de Bola 12 Toques em ao menos uma de suas categorias, quebrando assim, uma sequencia de t\u00edtulos que durava desde a temporada 2004.<\/p>\n<p>O pr\u00f3ximo compromisso dos atletas vasca\u00ednos na 12 Toques ser\u00e1 a disputa do Campeonato Brasileiro Interclubes, em suas categorias Principal e Master. Os nacionais ser\u00e3o realizados nos dias 15 e 16 de Novembro, sendo o principal em Po\u00e7os de Caldas &#8211; MG e o M\u00e1ster na sede cruz-maltina do Calabou\u00e7o no Rio de Janeiro &#8211; RJ.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foi realizada neste \u00faltimo final de semana, 26 e 27\/10, na AABB-Tijuca, a \u00faltima etapa do estadual individual da modalidade Bola 12 Toques. Ramos do CRVG terminou a etapa na 2\u00aa coloca\u00e7\u00e3o, assegurando assim a 3\u00aa coloca\u00e7\u00e3o do Estadual Individual 2013. Destaque ainda para Rodolfo (CRVG) que terminou o estadual na 4\u00aa coloca\u00e7\u00e3o. Armando do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[70,5],"tags":[],"class_list":["post-610","post","type-post","status-publish","format-standard","hentry","category-estaduais-individuais-2013","category-modalidade-bola-12","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/610"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=610"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/610\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}