{"id":691,"date":"2013-03-30T10:52:00","date_gmt":"2013-03-30T13:52:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2013\/03\/30\/marcell-e-rodolfo-classificados-na-copa-do-brasil-modalidade-bola-12-toques\/"},"modified":"2013-03-30T10:52:00","modified_gmt":"2013-03-30T13:52:00","slug":"marcell-e-rodolfo-classificados-na-copa-do-brasil-modalidade-bola-12-toques","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2013\/03\/30\/marcell-e-rodolfo-classificados-na-copa-do-brasil-modalidade-bola-12-toques\/","title":{"rendered":"MARCELL E RODOLFO CLASSIFICADOS NA COPA DO BRASIL &#8211; MODALIDADE BOLA 12 TOQUES"},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/1.bp.blogspot.com\/-mb6bzSx5TOY\/UVbrh-asezI\/AAAAAAAADM0\/X6KYawdEarg\/s1600\/cOPA+DO+bRASIL+2013+fRIBURGO+2.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"240\" src=\"http:\/\/1.bp.blogspot.com\/-mb6bzSx5TOY\/UVbrh-asezI\/AAAAAAAADM0\/X6KYawdEarg\/s320\/cOPA+DO+bRASIL+2013+fRIBURGO+2.jpg\" width=\"320\" \/><\/a><\/div>\n<div><\/div>\n<div>Encerrado o primeiro dia de jogos da 10\u00aa Copa do Brasil da Modalidade Bola 12 Toques, que est\u00e1 sendo realizada na cidade de Nova Friburgo no Estado do Rio de Janeiro, os atletas vasca\u00ednos Marcell Romero e Rodolfo Branco conseguiram classifica\u00e7\u00e3o em suas respectivas categorias para a disputa da s\u00e9rie Ouro.<\/div>\n<div><\/div>\n<div>Agora, s\u00f3 restam 16 competidores em cada s\u00e9rie, divididos em 2 grupos de 8 onde os 4 melhores avan\u00e7am na luta pelo t\u00edtulo.<\/div>\n<div><\/div>\n<div>Na categoria Adulto o atleta vasca\u00edno Marcell Romero disputar\u00e1 a vaga com Tadeu &#8211; Corinthians-SP, Thiago &#8211; C\u00edrculo Militar-SP, Bruno Varoli &#8211; C\u00edrculo Militar &#8211; SP, Robertinho &#8211; Curitibano-PR, Vin\u00edcius &#8211; Friburguense, Pablo &#8211; Friburguense e Pedreira do America-RJ.<\/div>\n<div><\/div>\n<div>Na categoria M\u00e1ster, os grupos ainda n\u00e3o foram divulgados.<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Encerrado o primeiro dia de jogos da 10\u00aa Copa do Brasil da Modalidade Bola 12 Toques, que est\u00e1 sendo realizada na cidade de Nova Friburgo no Estado do Rio de Janeiro, os atletas vasca\u00ednos Marcell Romero e Rodolfo Branco conseguiram classifica\u00e7\u00e3o em suas respectivas categorias para a disputa da s\u00e9rie Ouro. Agora, s\u00f3 restam 16 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[5,72],"tags":[],"class_list":["post-691","post","type-post","status-publish","format-standard","hentry","category-modalidade-bola-12","category-nacionais-individuais-2013","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/691"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=691"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/691\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}