{"id":783,"date":"2012-06-14T16:55:00","date_gmt":"2012-06-14T19:55:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2012\/06\/14\/dupla-vascaina-conquista-3o-lugar-no-mundial-de-futmesa-modalidade-sectorball\/"},"modified":"2012-06-14T16:55:00","modified_gmt":"2012-06-14T19:55:00","slug":"dupla-vascaina-conquista-3o-lugar-no-mundial-de-futmesa-modalidade-sectorball","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2012\/06\/14\/dupla-vascaina-conquista-3o-lugar-no-mundial-de-futmesa-modalidade-sectorball\/","title":{"rendered":"DUPLA VASCA\u00cdNA CONQUISTA 3\u00ba LUGAR NO MUNDIAL DE FUTMESA &#8211; MODALIDADE SECTORBALL"},"content":{"rendered":"<p><a href=\"http:\/\/4.bp.blogspot.com\/-IyJ_GdfAYGk\/T9pB0rOVPMI\/AAAAAAAACOk\/Qe_DUzZGM04\/s1600\/Marcelo%2BLages%2BBrasil%2BDuplas.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5753983847131069634\" src=\"http:\/\/4.bp.blogspot.com\/-IyJ_GdfAYGk\/T9pB0rOVPMI\/AAAAAAAACOk\/Qe_DUzZGM04\/s320\/Marcelo%2BLages%2BBrasil%2BDuplas.jpg\" style=\"cursor: hand; cursor: pointer; display: block; height: 213px; margin: 0px auto 10px; text-align: center; width: 320px;\" \/><\/a><\/p>\n<p>A dupla brasileira formada por Marcelo Lages e Igor Monteiro, ambos do Vasco da Gama, fizeram hist\u00f3ria no Sector Ball, conquistando a terceira coloca\u00e7\u00e3o no Campeonato Mundial da modalidade, disputado no dia 8 de junho no CIB &#8211; Clube Israelita Brasileiro, em Copacabana. Eles ficaram no terceiro lugar com duas vit\u00f3rias, duas derrotas e dois empates.<\/p>\n<p>1\u00aa FASE<\/p>\n<p>2 x 0 Bruno Coutinho\/Barthez(BRASIL)<br \/>1 X 2 Lukacs\/Szatmari(HUNGRIA)<br \/>1 X 1 Borcsok\/Plemic (S\u00c9RVIA)<\/p>\n<p>QUARTAS DE FINAL<\/p>\n<p>1 X 1 Inre\/karoly* (HUNGRIA)<\/p>\n<p>SEMI-FINAL<\/p>\n<p>0 X 1 Martonfi\/Koszta(ROM\u00caNIA)<\/p>\n<p>DISPUTA DE 3\u00ba LUGAR<\/p>\n<p>2 X 1 Ramjanac\/Kristic(S\u00c9RVIA)<\/p>\n<p>Esse foi o melhor resultado brasileiro na competi\u00e7\u00e3o de duplas da modalidade Sectorball, regra de origem europ\u00e9ia, disputada no Brasil desde 2010. A dupla cruz-maltina formada por Robson Marfa e Weber Gomes, foi eliminada nas quartas de final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A dupla brasileira formada por Marcelo Lages e Igor Monteiro, ambos do Vasco da Gama, fizeram hist\u00f3ria no Sector Ball, conquistando a terceira coloca\u00e7\u00e3o no Campeonato Mundial da modalidade, disputado no dia 8 de junho no CIB &#8211; Clube Israelita Brasileiro, em Copacabana. Eles ficaram no terceiro lugar com duas vit\u00f3rias, duas derrotas e dois [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[12,54],"tags":[],"class_list":["post-783","post","type-post","status-publish","format-standard","hentry","category-modalidade-sectorball","category-selecao-brasileira","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/783"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}