{"id":800,"date":"2012-05-22T09:34:00","date_gmt":"2012-05-22T12:34:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2012\/05\/22\/marcelo-lages-e-campeao-do-ii-brazils-international-open-modalidade-sectorball\/"},"modified":"2012-05-22T09:34:00","modified_gmt":"2012-05-22T12:34:00","slug":"marcelo-lages-e-campeao-do-ii-brazils-international-open-modalidade-sectorball","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2012\/05\/22\/marcelo-lages-e-campeao-do-ii-brazils-international-open-modalidade-sectorball\/","title":{"rendered":"MARCELO LAGES \u00c9 CAMPE\u00c3O DO II BRAZIL&#8217;S INTERNATIONAL OPEN &#8211; MODALIDADE SECTORBALL"},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/1.bp.blogspot.com\/-kV5_0sZjnx0\/T7uHgL4f7_I\/AAAAAAAACKk\/C1sUO168RfY\/s1600\/International_Open_2012.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"240\" src=\"http:\/\/1.bp.blogspot.com\/-kV5_0sZjnx0\/T7uHgL4f7_I\/AAAAAAAACKk\/C1sUO168RfY\/s320\/International_Open_2012.jpg\" width=\"320\" \/><\/a><\/div>\n<p>Aproveitando a chegada dos times enviados pela Gesini Futebol de Mesa, foi realizado no s\u00e1bado, 12\/05, o II Brazil&#8217;s International Open, na Divis\u00e3o de Futebol de Mesa do CR Vasco da Gama.<\/p>\n<p>A primeira edi\u00e7\u00e3o deste evento foi realizada ano passado, contando com a participa\u00e7\u00e3o de Horv\u00e1th Imre, da Hungria, Presidente da ISBF. Na edi\u00e7\u00e3o deste ano estiveram presentes apenas atletas que estar\u00e3o no pr\u00f3ximo Campeonato Mundial, representando Brasil, Canad\u00e1 e Portugal.<\/p>\n<p>O grande objetivo era testar os novos times fornecidos pela Gesini, patrocinadora oficial da equipe brasileira. At\u00e9 aqui todo o material utilizado era importado da Hungria e, pela primeira vez, bot\u00f5es de Sectorball est\u00e3o sendo produzidos no Brasil.<\/p>\n<p>Todos os participantes adaptaram-se rapidamente aos novos times e os elogios \u00e0 jogabilidade dos bot\u00f5es foi un\u00e2nime. Com esta parceria entre Gesini e CBFM, sem d\u00favida a equipe brasileira encontra-se agora muito melhor preparada para uma participa\u00e7\u00e3o marcante no Mundial!<\/p>\n<p>A classifica\u00e7\u00e3o final do II Brazil&#8217;s International Open foi:<\/p>\n<p>1\u00ba) Marcelo Lages (Brasil)<br \/>2\u00ba) Marcelo Coutinho (Brasil)<br \/>3\u00ba) Felipe Godinho (Brasil)<br \/>4\u00ba) Alexandre Machado (Canad\u00e1)<br \/>5\u00ba) Alexandre Lages (Portugal)<br \/>6\u00ba) Raphael Couto (Portugal)<\/p>\n<p>Confira como ficou o hist\u00f3rico de campe\u00f5es da competi\u00e7\u00e3o internacional:<\/p>\n<p>2012 &#8211; Marcelo Lages &#8211; Brasil<br \/>2011 &#8211; Horv\u00e1th Imre &#8211; Hungria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aproveitando a chegada dos times enviados pela Gesini Futebol de Mesa, foi realizado no s\u00e1bado, 12\/05, o II Brazil&#8217;s International Open, na Divis\u00e3o de Futebol de Mesa do CR Vasco da Gama. A primeira edi\u00e7\u00e3o deste evento foi realizada ano passado, contando com a participa\u00e7\u00e3o de Horv\u00e1th Imre, da Hungria, Presidente da ISBF. Na edi\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[12],"tags":[],"class_list":["post-800","post","type-post","status-publish","format-standard","hentry","category-modalidade-sectorball","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/800"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=800"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/800\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}