{"id":878,"date":"2011-12-07T18:38:00","date_gmt":"2011-12-07T20:38:00","guid":{"rendered":"https:\/\/futmesavasco.com.br\/index.php\/2011\/12\/07\/vascainos-disputam-etapa-decisiva-no-sectorball\/"},"modified":"2011-12-07T18:38:00","modified_gmt":"2011-12-07T20:38:00","slug":"vascainos-disputam-etapa-decisiva-no-sectorball","status":"publish","type":"post","link":"https:\/\/futmesavasco.com.br\/index.php\/2011\/12\/07\/vascainos-disputam-etapa-decisiva-no-sectorball\/","title":{"rendered":"VASCA\u00cdNOS DISPUTAM ETAPA DECISIVA NO SECTORBALL"},"content":{"rendered":"<p><a href=\"http:\/\/3.bp.blogspot.com\/-BS1UqvjXr6E\/Tt_dmyiyuDI\/AAAAAAAABZU\/_7xgbYBknvI\/s1600\/Sectorball%2B-%2BFefumerj%2B-%2B5.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5683504913237325874\" src=\"http:\/\/3.bp.blogspot.com\/-BS1UqvjXr6E\/Tt_dmyiyuDI\/AAAAAAAABZU\/_7xgbYBknvI\/s320\/Sectorball%2B-%2BFefumerj%2B-%2B5.jpg\" style=\"cursor: hand; cursor: pointer; display: block; height: 213px; margin: 0px auto 10px; text-align: center; width: 320px;\" \/><\/a><\/p>\n<div style=\"text-align: justify;\">Ser\u00e1 realizada no pr\u00f3ximo domingo (11\/12) na Divis\u00e3o de Futebol de Mesa do CR Vasco da Gama, o 2\u00ba Turno do Campeonato Estadual Individual da Modalidade Sectorball.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">O atleta cruz-maltino Weber Gomes conquistou o 1\u00ba turno, podendo chegar ao Bi-Campeonato Estadual sem a necessidade de uma final caso conquiste tamb\u00e9m o 2\u00ba turno. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Para os demais atletas inscritos no estadual individual da modalidade, resta a miss\u00e3o de conquistar o 2\u00ba turno e for\u00e7ar uma partida decisiva para conhecermos o campe\u00e3o estadual da temporada.  Vale lembrar que a partida final, caso seja necess\u00e1ria, ser\u00e1 realizada na mesma data.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Al\u00e9m de Weber Gomes, o gigante da colina dever\u00e1 contar com a presen\u00e7a dos atletas, Igor Monteiro, Marcelo Lages, Robson Marfa e Thiago.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ao t\u00e9rmino da competi\u00e7\u00e3o ser\u00e1 realizada a entrega da premia\u00e7\u00e3o de toda a temporada.<\/div>\n<div style=\"text-align: justify;\"><span><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"background-color: white; color: #333333; line-height: 20px;\"><span>Nota: O Sectorball trata-se de uma variante internacional do Futebol de Mesa de origem no leste europeu, mais precisamente na Hungria. A Federa\u00e7\u00e3o de Futebol de Mesa do Estado do Rio de Janeiro incluiu a modalidade em seu quadro a partir da temporada de 2010, realizando as primeiras competi\u00e7\u00f5es visando a prepara\u00e7\u00e3o para o Mundial a ser realizado no ano de 2012 no Rio de Janeiro.<\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 realizada no pr\u00f3ximo domingo (11\/12) na Divis\u00e3o de Futebol de Mesa do CR Vasco da Gama, o 2\u00ba Turno do Campeonato Estadual Individual da Modalidade Sectorball. O atleta cruz-maltino Weber Gomes conquistou o 1\u00ba turno, podendo chegar ao Bi-Campeonato Estadual sem a necessidade de uma final caso conquiste tamb\u00e9m o 2\u00ba turno. Para os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[80,12],"tags":[],"class_list":["post-878","post","type-post","status-publish","format-standard","hentry","category-estaduais-individuais-2011","category-modalidade-sectorball","entry"],"_links":{"self":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/878"}],"collection":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=878"}],"version-history":[{"count":0,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/878\/revisions"}],"wp:attachment":[{"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futmesavasco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}